{"id":89661,"date":"2022-11-29T15:31:07","date_gmt":"2022-11-29T15:31:07","guid":{"rendered":"https:\/\/rotavicentina.com\/ueber-die-region\/"},"modified":"2023-01-23T20:59:48","modified_gmt":"2023-01-23T20:59:48","slug":"ueber-die-region","status":"publish","type":"page","link":"https:\/\/rotavicentina.com\/de\/ueber-die-region\/","title":{"rendered":"\u00dcber die Region"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; back_image=&#8220;79123&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; row_height_pixel=&#8220;465px&#8220;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-end&#8220; style=&#8220;dark&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading auto_text=&#8220;yes&#8220; heading_semantic=&#8220;h1&#8243; text_size=&#8220;&#8220; el_class=&#8220;alternative-font big-title&#8220;]\u00dcber die Region[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243; mobile_order=&#8220;2&#8243;][vc_custom_heading text_weight=&#8220;font-weight-medium&#8220; css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;title-stroked mt-adapt-3&#8243;]S\u00fcdwest-<del><ins>Portugal<\/ins><\/del>[\/vc_custom_heading][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243;]110 km wilde K\u00fcste[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;2&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243; mobile_order=&#8220;2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mt-adapt-5&#8243;]110 <strong>km wilde K\u00fcste<\/strong> und zirka <strong>75000 Hektar<\/strong> gesch\u00fctztes Gebiet bilden das <strong>Naturreservat Parque Natural do Sudoeste Alentejano e Costa Vicentina.<\/strong>Es besteht aus einer Vielfalt an Lebensr\u00e4umen, die zum Teil noch fast unber\u00fchrt sind und etliche endemische Pflanzenarten sowie eine gro\u00dfe <strong>Zahl an Tierspezies<\/strong> haupts\u00e4chlich Amphibien, V\u00f6gel und Meerestiere aufweisen.[\/vc_column_text][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mt-adapt-5&#8243;]Der Naturpark verbindet zwei besonders reizvolle Regionen Portugals: die romantische und ruhige <strong>Alentejo<\/strong>-K\u00fcste mit dem in einzigartiger Weise urspr\u00fcnglichen und wilden K\u00fcstenstreifen der <strong>Algarve<\/strong>. Wildnis, Landwirtschaft und ein angenehmes Klima, in dem die Sonne an mehr als 300 Tagen im Jahr scheint, gestalten diese Region zu einem attraktiven Ziel f\u00fcr Urlauber, die Authentisches suchen und den Naturtourismus bevorzugen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;1&#8243; bottom_padding=&#8220;2&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/3&#8243; el_class=&#8220;mt-adapt-4&#8243;][vc_single_image media=&#8220;79137&#8243;][\/vc_single_image][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/3&#8243; el_class=&#8220;mt-adapt-4&#8243;][vc_single_image media=&#8220;79141&#8243;][\/vc_single_image][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/3&#8243; el_class=&#8220;mt-adapt-4&#8243;][vc_single_image media=&#8220;79145&#8243;][\/vc_single_image][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;4&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243; mobile_order=&#8220;2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mt-adapt-5&#8243;]<strong>Wer sich vom Meer aus dem S\u00fcdwesten Portugals n\u00e4hert, st\u00f6\u00dft auf eine hohe Klip- penlandschaft mit Felsformationen aus uraltem Gestein, dunkel an der Alentejo-K\u00fcste (Schiefer und Grauwacke) und hell an der Algarve-K\u00fcste (Kalk). Auf der K\u00fcstenebene ist der felsige Untergrund mit einer feinen Sedimentschicht \u00fcberzogen, dem N\u00e4hrboden einer F\u00fclle von Lebensr\u00e4umen und einzigartigen Spezies.<\/strong>[\/vc_column_text][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mt-adapt-5&#8243;]Fl\u00fcsse und B\u00e4che durchziehen das K\u00fcstenplateau mit tiefen Schluchten und T\u00e4lern und ihre Ufer sind ges\u00e4umt von mediterranem Dickicht, das noch fast unber\u00fchrt ist. Weiter im Landesinneren schlie\u00dft sich eine Berglandschaft, die Serra an, deren Felsfalten durch gewaltige Verschiebungen der Kontinentalplatten geformt wurden. Eichen- und Kiefernw\u00e4lder sowie felsige Bergkuppen pr\u00e4gen diese Landschaft, die von Greifv\u00f6geln und nachtaktiven Raubtieren bev\u00f6lkert ist.[\/vc_column_text][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; columns_gutter=&#8220;&#8220; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; el_class=&#8220;mb-adapt-8 mb-adapt-md-0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;5\/12&#8243; mobile_order=&#8220;1&#8243;][vc_single_image media_div=&#8220;background&#8220; media=&#8220;79133&#8243; css_animation=&#8220;masked&#8220;][\/vc_single_image][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_visibility=&#8220;yes&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/12&#8243;][\/vc_column][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243; mobile_order=&#8220;2&#8243; el_class=&#8220;pt-adapt-4 pb-adapt-4&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220;]Den S\u00fcdwesten Portugals zeichnen seit jeher \u2013 seit tausenden von Jahren \u2013 global au\u00dfergew\u00f6hnlich g\u00fcnstige klimatische Bedingungen aus. Ein Indiz daf\u00fcr ist die Tatsache, dass dieses Gebiet in den letzten Eiszeiten ein Refugium vieler Pflanzen- und Tierarten war, von denen ein gro\u00dfer Teil bis heute dort zu finden ist, auch wenn weitere Populationen dieser Spezies erst wieder hunderte von Kilometern entfernt existieren. Im S\u00fcdwesten Portugals gibt es zudem etliche endemische Arten, die weltweit also nur dort vorkommen.<\/p>\n<p>Die Winter sind kurz und mild, bringen aber gen\u00fcgend Regen, um die Erde f\u00fcr die verbleibenden neun Sonnenmonate mit Wasser zu versorgen. Die Harmonie, in der Natur und Mensch seit der Urgeschichte dort zusammenleben, zeigt sich an der Vielfalt der vorhandenen Habitate, in denen man auf Entdeckungstour gehen kann:[\/vc_column_text][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; columns_gutter=&#8220;&#8220; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; el_class=&#8220;mb-adapt-8 mb-adapt-md-0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243; mobile_order=&#8220;2&#8243; el_class=&#8220;pt-adapt-4 pb-adapt-4&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mt-adapt-4&#8243;]bei Ebbe zwischen den Felsen (Seesterne, Seeigel, Entenmuscheln und Wellhornschnecken \u2026), an den dunklen Klippen des Alentejo (wo St\u00f6rche, Falken, Schwalben, Dohlen, Hausrotschw\u00e4nze, \u2026 nisten), an den wei\u00dfen Klippen der Algarve (wo man Fu\u00dfspuren von Dinosauriern, fossile Korallen und dunkle Grotten mit sagenhaften Wesen findet), in den D\u00fcnen (reich an seltenen, endemischen, aromatischen und Heilpflanzen \u2026), an den Fluss- und Bachm\u00fcndungen (Brutst\u00e4tten f\u00fcr Fische, Weich- und Schalentiere); auf den K\u00fcstenplateaus (im Oktober Schauplatz zur Beobachtung tausender Zugv\u00f6gel inklusive der gro\u00dfen Gleitflieger), an den tempor\u00e4ren mediterranen Flachgew\u00e4ssern (bev\u00f6lkert von pr\u00e4historischen Schalentieren sowie nahezu allen in Portugal heimischen Amphibien), in abgelegenen T\u00e4lern (mit portugiesischen Eichen, Lianen und Buschwerk voller bunter Beeren), an klaren Bachl\u00e4ufen (in denen der Otter heimisch ist); oder in Pinien- und Korkeichenw\u00e4ldern (Lebensraum der Wildschweine, ideal zum Sammeln von Pilzen und wildem Spargel). Selbst in den vom Menschen kultivierten Landschaften bewahrt sich in Korkeichen- und Olivenhainen, auf Wiesen und in Obstplantagen eine gro\u00dfe biologische Vielfalt.[\/vc_column_text][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_visibility=&#8220;yes&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/12&#8243;][\/vc_column][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;5\/12&#8243; mobile_order=&#8220;1&#8243;][vc_single_image media_div=&#8220;background&#8220; media=&#8220;79129&#8243; css_animation=&#8220;masked&#8220;][\/vc_single_image][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; columns_gutter=&#8220;&#8220; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; el_class=&#8220;mb-adapt-8 mb-adapt-md-0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;5\/12&#8243; mobile_order=&#8220;1&#8243;][vc_video video_link=&#8220;https:\/\/youtu.be\/8cTi3Ux7vQE&#8220;][\/vc_column][vc_column position_horizontal=&#8220;&#8220; mobile_visibility=&#8220;yes&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/12&#8243;][\/vc_column][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/2&#8243; mobile_order=&#8220;2&#8243; el_class=&#8220;pt-adapt-4 pb-adapt-4&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220;]In den D\u00f6rfern bewahren gastfreundliche Menschen jahrhundertealte Traditionen, wie beispielsweise die Kork- und Honiggewinnung, den Weinanbau, die Oliven\u00f6l-Herstellung, die T\u00f6pferei und den Fischfang.<\/p>\n<p>Die eindrucksvollsten Merkmale auf der Rota Vicentina pr\u00e4sentiert die Natur, aber die menschliche Geschichte findet sich ebenfalls in vielen arch\u00e4ologischen Spuren, heiligen St\u00e4tten voller Mystik, Festungen, die vor Piraten sch\u00fctzten oder in einer Inschrift, die bis heute nicht entschl\u00fcsselt werden konnte. Sie wurde auf Steintafeln gefunden, die mehr als 2.500 Jahre alt sind![\/vc_column_text][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;yes&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;4&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; el_class=&#8220;mt-adapt-8&#8243; back_color=&#8220;#b2c39d&#8220;][vc_column width=&#8220;1\/1&#8243;][vc_row_inner unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;1&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column_inner position_horizontal=&#8220;&#8220; align_horizontal=&#8220;text-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading text_size=&#8220;h1&#8243; text_weight=&#8220;font-weight-normal&#8220; el_class=&#8220;alternative-font&#8220;]Wann zu besuchen[\/vc_custom_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;2&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mb-adapt-5&#8243;]<strong>Die idealen Wandermonate auf der Rota Vicentina sind September bis Juni.<\/strong><br \/>\nS\u00fcdwestPortugals mediterranes Klima verspricht ganzj\u00e4hrig milde Temperaturen, vor allem durch den starken Einfluss des Atlantik.<\/p>\n<p>Der Oktober ist im Allgemeinen sehr mild mit ebenfalls warmen Wassertemperaturen und kaum starkem Wind.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8220;1\/2&#8243;][vc_column_text css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;mb-adapt-5&#8243;]Im Winter sinken die Tagestemperaturen nicht unter 11\u00b0C. Gew\u00f6hnlich f\u00e4llt zu dieser Jahreszeit der meiste Regen.<\/p>\n<p>Ab M\u00e4rz wechseln Sonnen- und Regentage sich ab, w\u00e4hrend die Temperaturen zu steigen beginnen. Die Landschaft erwacht und die Intensit\u00e4t der Farben und D\u00fcfte sorgt daf\u00fcr, dass der Fr\u00fchling eine der sch\u00f6nsten Jahreszeiten f\u00fcr einen Besuch dieser Region ist.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_single_image media=&#8220;78820&#8243;][\/vc_single_image][vc_row_inner unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column_inner position_horizontal=&#8220;&#8220; align_horizontal=&#8220;text-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading text_size=&#8220;h1&#8243; text_weight=&#8220;font-weight-normal&#8220; el_class=&#8220;alternative-font&#8220;]Anreise und Transportmittel[\/vc_custom_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column_inner width=&#8220;1\/12&#8243;][\/vc_column_inner][vc_column_inner position_horizontal=&#8220;&#8220; override_padding=&#8220;yes&#8220; column_padding=&#8220;2&#8243; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;5\/6&#8243; back_color=&#8220;#ffffff&#8220; el_class=&#8220;radius-cell&#8220;][vc_accordion el_class=&#8220;limited-accordion mt-adapt-4 mb-adapt-6&#8243;][vc_accordion_tab title=&#8220;Mit dem flugzeug&#8220; tab_id=&#8220;1669738943840-0-3&#8243;][vc_column_text]Die Region wird von den Flugh\u00e4fen Lissabon und Faro ver- sorgt. F\u00fcr die n\u00f6rdlichen Etappen eignet sich der Anflug \u00fcber Lissabon am besten, f\u00fcr die s\u00fcdlichen Faro, wobei die Anschlussverbindungen ab Lissabon vielf\u00e4ltiger sind. Die Flugh\u00e4fen Lissabon und Faro werden von praktisch allen europ\u00e4ischen Hauptst\u00e4dten angeflogen.<\/p>\n<p><strong>Madrid \u2013 Faro: 1h00<\/strong><br \/>\n<strong>London \u2013 Faro: 2h30<\/strong><br \/>\n<strong>Berlin &#8211; Lissabon: 3h25<\/strong><br \/>\n<strong>Kopenhagen &#8211; Lissabon: 3h45<\/strong>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=&#8220;Mit dem auto&#8220; tab_id=&#8220;1669738949212-1-5&#8243;][vc_column_text]<strong>Von Lissabon<\/strong><br \/>\nVon Lissabon aus nehmen Sie die A2\/A12 oder IC1 in Richtung Sul\/Algarve. Es gibt mehrere Alternativen, wobei es in Bezug auf die Kilometerzahl oder die Fahrzeit keine gro\u00dfen Unterschiede gibt. W\u00e4hlen Sie zwischen:<\/p>\n<p><strong>Option 1<\/strong><br \/>\nBei km 104 der A2 nehmen Sie die IP8 in Richtung Sines. Auf der IC1, in Gr\u00e2ndola, nehmen Sie die gleiche Abfahrt. Folgen Sie den Schildern nach Odemira und Porto Covo. Dies ist eine gute Option, um Santiago do Cac\u00e9m, Sines, Porto Covo und Milfontes zu erreichen.<\/p>\n<p><strong>Option 2<\/strong><br \/>\nVon der A2 nehmen Sie bei Kilometer 119 die Ausfahrt &#8222;Beja\/Ferreira&#8220; und fahren auf die IC1 in Richtung &#8222;Algarve\/Ourique&#8220;. Auf der IC1 haben Sie die M\u00f6glichkeit, in Richtung &#8222;Santiago do Cac\u00e9m\/Sines&#8220; abzufahren. Dann nehmen Sie die Ausfahrt &#8222;Alvalade \/ Cercal \/ Lagos&#8220;, ideal, wenn Sie die Orte Cercal, S. Lu\u00eds und Vila Nova de Milfontes besuchen m\u00f6chten. Alternativ k\u00f6nnen Sie die Ausfahrt &#8222;Odemira \/ OESTE&#8220; nehmen. Wenn Sie in Odemira ankommen, befinden Sie sich auf der N120, die alle Orte der Rota Vicentina im S\u00fcdwestens durchquert: Cercal, S\u00e3o Lu\u00eds, Odemira, S\u00e3o Teot\u00f3nio, Odeceixe, Aljezur, usw.<\/p>\n<p><strong>Von Faro<\/strong><br \/>\nNehmen Sie die A22 oder N125 nach Lagos\/Bensafrim.<\/p>\n<p><strong>Richtung Aljezur\/Odeceixe<\/strong><br \/>\nIn Lagos\/Bensafrim nehmen Sie die N120 nach Aljezur, Odeceixe, S\u00e3o Teot\u00f3nio, Odemira, S\u00e3o Lu\u00eds, Cercal und Santiago do Cac\u00e9m. In Odemira nehmen Sie die Abzweigung nach Portas de Transval &#8211; Richtung Almograve, Vila Nova de Milfontes und Porto Covo.<\/p>\n<p><strong>In Richtung Sagres\/Vila do Bispo\/Carrapateira<\/strong><br \/>\nVon Lagos aus fahren Sie auf der N125 nach Vila do Bispo, von wo aus Sie nach S\u00fcden Richtung Sagres und Cabo de S\u00e3o Vicente oder nach Norden Richtung Carrapateira, Bordeira und Aljezur fahren k\u00f6nnen.<\/p>\n<p><strong>Einige Entfernungen<\/strong><\/p>\n<ul>\n<li>Lissabon &#8211; Sines: 165 km<\/li>\n<li>Lissabon \u2013 Odemira: 202 km<\/li>\n<li>Porto \u2013 Odemira: 478 km<\/li>\n<li>Faro \u2013 Odemira: 149 km<\/li>\n<li>Lissabon \u2013 Aljezur: 244 km<\/li>\n<li>Faro \u2013 Aljezur: 108 km<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=&#8220;Zug&#8220; tab_id=&#8220;1669739298693-2-4&#8243;][vc_column_text]Besonders umweltfreundlich, effizient und bequem reist es sich per Bahn in den S\u00fcdwesten. Mit Ausnahme von Lagos, wo der Fischerpfad startet oder endet, befinden sich die Bahnstationen der Algarve meist weiter von der K\u00fcste entfernt. Nutzen Sie die Gelegenheit, eine oder mehrere N\u00e4chte in der N\u00e4he des Santa Clara-Staudamms zu verbringen und beginnen Sie Ihre Unternehmung in einer weniger bekannten Umgebung der Region.<\/p>\n<p><strong>Von Lissabon<\/strong><br \/>\nAbfahrt von Lissabon-Entrecampos oder Lissabon-Oriente in Richtung Ermidas-Sado (+\/- 1h30m), Funcheira (+\/- 1h50m), S\u00e3o Martinho das Amoreiras (+\/- 2h), Santa Clara-Sab\u00f3ia (+\/- 2h15m), 3 mal t\u00e4glich zwischen 10h und 17h. <a href=\"https:\/\/www.cp.pt\/passageiros\/pt\" target=\"_blank\" rel=\"noopener\"><strong>Fahrpl\u00e4ne<\/strong><\/a><\/p>\n<p><strong>Vom Faro<\/strong><br \/>\nAbfahrten von Faro nach Lagos (+\/- 1h45), 9 Mal t\u00e4glich zwischen 7 und 20 Uhr, von wo aus Sie einen Bus zu Ihrem gew\u00fcnschten Zielort nehmen sollten. <a href=\"https:\/\/www.cp.pt\/passageiros\/pt\" target=\"_blank\" rel=\"noopener\"><strong>Fahrpl\u00e4ne<\/strong><\/a><\/p>\n<p>Abfahrten von Faro nach Santa Clara-Sab\u00f3ia (+\/- 1h), S\u00e3o Martinho das Amoreiras (+\/- 1h30m), Funcheira (+\/- 1h45) und Ermidas-Sado (+\/- 2h), 4 Mal t\u00e4glich zwischen 7 Uhr und 17.40 Uhr. <a href=\"https:\/\/www.cp.pt\/passageiros\/pt\" target=\"_blank\" rel=\"noopener\"><strong>Fahrpl\u00e4ne<\/strong><\/a><\/p>\n<p><strong>Vom Bahnhof zur K\u00fcste<\/strong><br \/>\nDer Bahnhof Ermidas-Sado liegt 30 km von Santiago do Cac\u00e9m entfernt. Von Odemira sind es 36 km bis Funcheira und 31 km bis S\u00e3o Martinho das Amoreiras. Santa Clara-Sab\u00f3ia ist 27 km von S\u00e3o Teot\u00f3nio entfernt. Siehe Tabelle der Entfernungen in der Region.<\/p>\n<p>Um an die K\u00fcste zu gelangen, k\u00f6nnen Sie zwischen einem unserer <a href=\"https:\/\/rotavicentina.com\/transportes\/\"><strong>Partnertaxis<\/strong><\/a> (+\/- 1\u20ac\/km), einem, von der gew\u00e4hlten Unterkunft angebotenen Transferservice oder den <strong><a href=\"https:\/\/www.rodalentejo.pt\/html\/default.asp\" target=\"_blank\" rel=\"noopener\">Buslinien im Alentejo<\/a><\/strong> w\u00e4hlen, und zwar unter der Woche, von Montag bis Freitag.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=&#8220;Mit dem bus&#8220; tab_id=&#8220;1669739312005-3-9&#8243;][vc_column_text]Dies ist der direkteste Weg, um jeden Punkt der Rota Vicentina zu erreichen. <a href=\"https:\/\/rede-expressos.pt\/pt\" target=\"_blank\" rel=\"noopener\"><strong>Rede Expressos<\/strong><\/a> verf\u00fcgt \u00fcber komfortable Busse mit kostenlosem Wi-Fi. Der einzige Nachteil ist, dass man einige Kilometer auf kurvenreichen Stra\u00dfen fahren muss und 1 bis 2 Stunden l\u00e4nger braucht als mit dem eigenen Auto.<\/p>\n<p><strong>Von Lissabon<\/strong><br \/>\nAbfahrt von Sete Rios in Richtung der gr\u00f6\u00dferen Orte der Region (Santiago do Cac\u00e9m &#8211; 2h20; Porto Covo &#8211; 3h; S. Teot\u00f3nio &#8211; 4h20m oder Aljezur &#8211; 5h). Je nach gew\u00e4hltem Ziel gibt es fahrplanm\u00e4\u00dfige Z\u00fcge, die alle an den gr\u00f6\u00dferen Orten im S\u00fcdwesten halten: in Santiago do Cac\u00e9m, wo der <strong><a href=\"https:\/\/rotavicentina.com\/caminho-historico\/\">Historische Weg<\/a><\/strong> beginnt, oder in Porto Covo, wo der <strong><a href=\"https:\/\/rotavicentina.com\/trilho-dos-pescadores\/\">Fischerpfad<\/a><\/strong> startet &#8211; jeweils von Norden aus gesehen. W\u00e4hlen Sie Ihren Abfahrts- und Zielort und planen Sie Ihre Reise.<\/p>\n<p><strong>Von Faro<\/strong><br \/>\nAbfahrten zwischen 8 Uhr und 17.25 Uhr in Richtung Lagos (2h10), mit VAMUS Algarve. Von Lagos gibt es nationale Verbindungen mit Rede Expressos und lokale Verbindungen <strong><a href=\"https:\/\/vamusalgarve.pt\/#\/\" target=\"_blank\" rel=\"noopener\">(VAMUS Algarve)<\/a><\/strong> zum Kap S\u00e3o Vicente, Sagres und Vila do Bispo, Aljezur, Rogil und Odeceixe.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=&#8220;Mit dem Fahrrad&#8220; tab_id=&#8220;1671575743907-5-5&#8243; slug=&#8220;bicicleta&#8220;][vc_column_text]Demn\u00e4chst verf\u00fcgbar.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab title=&#8220;In der Region&#8220; tab_id=&#8220;1669739321895-4-1&#8243;][vc_column_text]Die effizienteste M\u00f6glichkeit, um Passagiere und Gep\u00e4ck zu transportieren, oder auch f\u00fcr Transfers vom Flughafen zu einem beliebigen Ort auf der Rota Vicentina bieten unsere Partner-Taxis. Anhand der <a href=\"https:\/\/rotavicentina.com\/downloads\/\"><strong>Entfernungstabelle von Rota Vicentina<\/strong><\/a> k\u00f6nnen Sie die Kosten f\u00fcr den Taxi-Dienst einsch\u00e4tzen und dann unsere Service-Partner direkt kontaktieren.<\/p>\n<p>Die Buslinie <a href=\"https:\/\/www.rodalentejo.pt\/html\/default.asp\" target=\"_blank\" rel=\"noopener\"><strong>\u201eRodovi\u00e1ria do Alentejo\u201c<\/strong><\/a> bietet Verbindungen zwischen Odeceixe und Santiago do Cac\u00e9m, und <a href=\"https:\/\/vamusalgarve.pt\/#\/\" target=\"_blank\" rel=\"noopener\"><strong>\u201eVAMUS Algarve\u201c<\/strong><\/a> bietet Verbindungen zwischen Lagos und Odeceixe. Alternativ k\u00f6nnen Sie auch die Fernverbindungen von <a href=\"https:\/\/rede-expressos.pt\/pt\" target=\"_blank\" rel=\"noopener\"><strong>\u201eRede Expressos\u201c<\/strong><\/a> nutzen, um von einem Ort zum anderen zu gelangen. Einige dieser Verbindungen sind nur von Montag bis Freitag verf\u00fcgbar.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][\/vc_column_inner][vc_column_inner width=&#8220;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/1&#8243;][miew_block id=&#8220;126&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; back_image=&#8220;79123&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; row_height_pixel=&#8220;465px&#8220;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-end&#8220; style=&#8220;dark&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading auto_text=&#8220;yes&#8220; heading_semantic=&#8220;h1&#8243; text_size=&#8220;&#8220; el_class=&#8220;alternative-font big-title&#8220;]\u00dcber die Region[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243; mobile_order=&#8220;2&#8243;][vc_custom_heading text_weight=&#8220;font-weight-medium&#8220; css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;title-stroked mt-adapt-3&#8243;]S\u00fcdwest-Portugal[\/vc_custom_heading][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243;]110 km wilde K\u00fcste[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;2&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page-category":[],"class_list":["post-89661","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.5 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00dcber die Region - Rota Vicentina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rotavicentina.com\/de\/ueber-die-region\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber die Region - Rota Vicentina\" \/>\n<meta property=\"og:description\" content=\"[vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; back_image=&#8220;79123&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; row_height_pixel=&#8220;465px&#8220;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-end&#8220; style=&#8220;dark&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading auto_text=&#8220;yes&#8220; heading_semantic=&#8220;h1&#8243; text_size=&#8220;&#8220; el_class=&#8220;alternative-font big-title&#8220;]\u00dcber die Region[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243; mobile_order=&#8220;2&#8243;][vc_custom_heading text_weight=&#8220;font-weight-medium&#8220; css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;title-stroked mt-adapt-3&#8243;]S\u00fcdwest-Portugal[\/vc_custom_heading][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243;]110 km wilde K\u00fcste[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;2&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rotavicentina.com\/de\/ueber-die-region\/\" \/>\n<meta property=\"og:site_name\" content=\"Rota Vicentina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rotavicentina\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T20:59:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RotaVicentina\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"14\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rotavicentina.com\/de\/ueber-die-region\/\",\"url\":\"https:\/\/rotavicentina.com\/de\/ueber-die-region\/\",\"name\":\"\u00dcber die Region - Rota Vicentina\",\"isPartOf\":{\"@id\":\"https:\/\/rotavicentina.com\/#website\"},\"datePublished\":\"2022-11-29T15:31:07+00:00\",\"dateModified\":\"2023-01-23T20:59:48+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rotavicentina.com\/de\/ueber-die-region\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rotavicentina.com\/#website\",\"url\":\"https:\/\/rotavicentina.com\/\",\"name\":\"Rota Vicentina\",\"description\":\"A p\u00e9 pelo Trilho dos Pescadores, Caminho Hist\u00f3rico ou Percursos Circulares ou v\u00e1 de bicicleta pelos mais de 1000km de Trilhos de Bicicleta na Rota Vicentina.\",\"publisher\":{\"@id\":\"https:\/\/rotavicentina.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rotavicentina.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rotavicentina.com\/#organization\",\"name\":\"Rota Vicentina\",\"url\":\"https:\/\/rotavicentina.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rotavicentina.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rotavicentina.com\/wp-content\/uploads\/2023\/02\/Rota-Vicentina-SW-Portugal.jpg\",\"contentUrl\":\"https:\/\/rotavicentina.com\/wp-content\/uploads\/2023\/02\/Rota-Vicentina-SW-Portugal.jpg\",\"width\":\"852\",\"height\":\"480\",\"caption\":\"Rota Vicentina\"},\"image\":{\"@id\":\"https:\/\/rotavicentina.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/rotavicentina\",\"https:\/\/x.com\/RotaVicentina\",\"https:\/\/www.instagram.com\/rotavicentina\/\",\"https:\/\/pt.linkedin.com\/company\/rota-vicentina\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00dcber die Region - Rota Vicentina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rotavicentina.com\/de\/ueber-die-region\/","og_locale":"de_DE","og_type":"article","og_title":"\u00dcber die Region - Rota Vicentina","og_description":"[vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; back_image=&#8220;79123&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; row_height_pixel=&#8220;465px&#8220;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-end&#8220; style=&#8220;dark&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243;][vc_custom_heading auto_text=&#8220;yes&#8220; heading_semantic=&#8220;h1&#8243; text_size=&#8220;&#8220; el_class=&#8220;alternative-font big-title&#8220;]\u00dcber die Region[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;4&#8243; bottom_padding=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243;][vc_column position_horizontal=&#8220;&#8220; position_vertical=&#8220;d-md-flex align-items-md-center&#8220; mobile_width=&#8220;11&#8243; shift_x=&#8220;0&#8243; shift_y=&#8220;0&#8243; z_index=&#8220;0&#8243; width=&#8220;1\/1&#8243; mobile_order=&#8220;2&#8243;][vc_custom_heading text_weight=&#8220;font-weight-medium&#8220; css_animation=&#8220;alpha-anim&#8220; el_class=&#8220;title-stroked mt-adapt-3&#8243;]S\u00fcdwest-Portugal[\/vc_custom_heading][vc_custom_heading heading_semantic=&#8220;h3&#8243; text_size=&#8220;h3&#8243;]110 km wilde K\u00fcste[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row unlock_row_content=&#8220;&#8220; row_height_percent=&#8220;0&#8243; override_padding=&#8220;yes&#8220; h_padding=&#8220;0&#8243; top_padding=&#8220;0&#8243; bottom_padding=&#8220;2&#8243; [&hellip;]","og_url":"https:\/\/rotavicentina.com\/de\/ueber-die-region\/","og_site_name":"Rota Vicentina","article_publisher":"https:\/\/www.facebook.com\/rotavicentina","article_modified_time":"2023-01-23T20:59:48+00:00","twitter_card":"summary_large_image","twitter_site":"@RotaVicentina","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"14\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rotavicentina.com\/de\/ueber-die-region\/","url":"https:\/\/rotavicentina.com\/de\/ueber-die-region\/","name":"\u00dcber die Region - Rota Vicentina","isPartOf":{"@id":"https:\/\/rotavicentina.com\/#website"},"datePublished":"2022-11-29T15:31:07+00:00","dateModified":"2023-01-23T20:59:48+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rotavicentina.com\/de\/ueber-die-region\/"]}]},{"@type":"WebSite","@id":"https:\/\/rotavicentina.com\/#website","url":"https:\/\/rotavicentina.com\/","name":"Rota Vicentina","description":"A p\u00e9 pelo Trilho dos Pescadores, Caminho Hist\u00f3rico ou Percursos Circulares ou v\u00e1 de bicicleta pelos mais de 1000km de Trilhos de Bicicleta na Rota Vicentina.","publisher":{"@id":"https:\/\/rotavicentina.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rotavicentina.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/rotavicentina.com\/#organization","name":"Rota Vicentina","url":"https:\/\/rotavicentina.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rotavicentina.com\/#\/schema\/logo\/image\/","url":"https:\/\/rotavicentina.com\/wp-content\/uploads\/2023\/02\/Rota-Vicentina-SW-Portugal.jpg","contentUrl":"https:\/\/rotavicentina.com\/wp-content\/uploads\/2023\/02\/Rota-Vicentina-SW-Portugal.jpg","width":"852","height":"480","caption":"Rota Vicentina"},"image":{"@id":"https:\/\/rotavicentina.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rotavicentina","https:\/\/x.com\/RotaVicentina","https:\/\/www.instagram.com\/rotavicentina\/","https:\/\/pt.linkedin.com\/company\/rota-vicentina"]}]}},"_links":{"self":[{"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/pages\/89661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/comments?post=89661"}],"version-history":[{"count":6,"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/pages\/89661\/revisions"}],"predecessor-version":[{"id":89673,"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/pages\/89661\/revisions\/89673"}],"wp:attachment":[{"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/media?parent=89661"}],"wp:term":[{"taxonomy":"page-category","embeddable":true,"href":"https:\/\/rotavicentina.com\/de\/wp-json\/wp\/v2\/page-category?post=89661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}